{"id":54777,"date":"2023-09-07T11:59:00","date_gmt":"2023-09-07T09:59:00","guid":{"rendered":"https:\/\/www.marcolin.com\/it\/stories\/non-categorizzato\/how-is-a-pair-of-glasses-created\/"},"modified":"2023-09-06T17:02:15","modified_gmt":"2023-09-06T15:02:15","slug":"come-nasce-un-paio-di-occhiali","status":"publish","type":"post","link":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/","title":{"rendered":"Come nasce un paio di occhiali?"},"content":{"rendered":"<div class=\"row padding--new-big wrapperContent\">\n    <div class=\"articleContent j-articleContent\">\n                <h2 class=\"articleContent__title\">\n            <span class=\"articleContent__titleUnderline j-titleUnderlineAnimation\">\n            La fase della burattatura            <\/span>\n        <\/h2>\n        <div class=\"articleContent__richtext\">\n            <p>Tonde, irregolari butterfly o cat-eye. E poi in metallo o in acetato, nere o colorate: sono gli infiniti modi in cui le montature possono incorniciare, valorizzandolo, il nostro sguardo. Non tutti sanno, per\u00f2, da quali e quanti speciali processi di lavorazione passa la realizzazione di un paio di occhiali. Lara Marogna, Group Style &amp; Product Development di Marcolin, ci illustra uno dei processi pi\u00f9 importanti e delicati: la burattatura. \u00abIl suo nome deriva da quello della macchina che viene utilizzata, il buratto. Si chiama cos\u00ec il macchinario cilindrico, chiamato anche \u201cbotte\u201d, diviso in vasche all\u2019interno delle quali, conclusa la sagomatura, vengono infilati i frontali e le aste che poi andranno a comporre l\u2019occhiale, insieme a legnetti di faggio e betulla di diverse dimensioni e a palline di pasta abrasiva. A questo punto la macchina viene chiusa e fatta partire: il buratto comincia a girare su s\u00e9 stesso ad una velocit\u00e0 che pu\u00f2 variare in base al materiale (metallo o acetato) e ad ogni rotazione, per caduta e sfregamento, legnetti e paste abrasive compiono il lavoro di sgrossatura, lucidatura e brillantatura finale delle montature\u00bb. Un lavoro lungo perch\u00e9, per ciascuna delle tre fasi, il buratto gira ininterrottamente da 12 fino a 14 ore.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"row padding--new-big wrapperContent\">\n    <div class=\"articleContent j-articleContent\">\n                <h2 class=\"articleContent__title\">\n            <span class=\"articleContent__titleUnderline j-titleUnderlineAnimation\">\n            L\u2019importanza del giusto mix            <\/span>\n        <\/h2>\n        <div class=\"articleContent__richtext\">\n            <p>\u00abA ogni passaggio, quando il buratto viene scaricato, sono gli operai a controllare una per una le montature. E al momento di ricaricarlo, devono saper dosare alla perfezione la quantit\u00e0 di legnetti e di pasta che compone il mix del materiale di lucidatura. E possono farlo verificando al tatto che non sia troppo secco n\u00e9 troppo oleoso; quindi, servono esperienza e conoscenza dei materiali. \u00c8 proprio dal giusto equilibrio di questi ingredienti, infatti, che si pu\u00f2 ottenere un risultato eccellente. Cio\u00e8 un occhiale in cui ogni dettaglio della montatura sia perfetto per la sua funzione, dunque resistente ma anche impeccabile dal punto di vista estetico\u00bb. E Lara Marogna, che ha iniziato il suo percorso professionale nel mondo della gioielleria, sa bene che \u00e8 dalla cura di queste fasi, che avvengono dietro le quinte di una fabbrica, che si pu\u00f2 ottenere un prodotto glamour ed elegante, in grado di farci sognare e di valorizzare il nostro stile personale.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"row padding--new-big wrapperContent\">\n    <div class=\"articleContent j-articleContent\">\n                <h2 class=\"articleContent__title\">\n            <span class=\"articleContent__titleUnderline j-titleUnderlineAnimation\">\n            Un viaggio a tre tappe            <\/span>\n        <\/h2>\n        <div class=\"articleContent__richtext\">\n            <p>Trascorso questo lasso di tempo, il buratto viene aperto e le montature controllate una ad una (per i non addetti ai lavori \u00e8 sorprendente vedere come, a ogni passaggio, le montature siano pi\u00f9 belle e brillanti). Successivamente, vengono infilate in un altro buratto, dove si avvia la fase successiva per altrettante 12-14 ore. In tutto, il processo richiede quattro giorni di lavoro per raggiungere il risultato finale di una montatura perfettamente levigata e brillante. Pronta per essere rifinita e uscire dalla fabbrica.<\/p>\n<p>Non si tratta per\u00f2 di un processo squisitamente meccanico, dove \u00e8 il buratto a fare tutto: a fare la differenza nella burattatura \u00e8 l\u2019aspetto umano, grazie agli occhi e alle mani degli operai che ne gestiscono e seguono tutto il processo.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"row padding--new-big wrapperContent\">\n    <div class=\"videoInline j-videoInline\">\n        <picture class=\"videoInline__picture\">\n            <source media=\"(max-width: 768px)\" srcset=\"https:\/\/www.marcolin.com\/wp-content\/uploads\/2023\/09\/burattatura-mobile.png\">\n            <source media=\"(max-width:2040px)\" srcset=\"https:\/\/www.marcolin.com\/wp-content\/uploads\/2023\/09\/burattatura-desktop.png\">\n            <img decoding=\"async\" class=\"videoInline__img\" src=\"https:\/\/www.marcolin.com\/wp-content\/uploads\/2023\/09\/burattatura-desktop.png\" alt=\"\">\n        <\/picture>\n        <!-- <video src=\"\"><\/video> -->\n        <button aria-label=\"play video\" class=\"videoInline__button j-videoInlinePlay\">\n            <svg width=\"81\" height=\"81\" viewBox=\"0 0 81 81\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M40.5 80C62.3152 80 80 62.3152 80 40.5C80 18.6848 62.3152 1 40.5 1C18.6848 1 1 18.6848 1 40.5C1 62.3152 18.6848 80 40.5 80Z\" stroke=\"white\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n                <path class=\"icon\" d=\"M28 40.5021V22.9724C28 20.6926 30.1672 19.2549 31.8949 20.4051L45.1846 29.1648L58.6889 38.0683C60.437 39.2185 60.437 41.7858 58.6889 42.936L45.1846 51.8395L31.8949 60.5992C30.1672 61.7391 28 60.3116 28 58.0319V40.5021Z\" stroke=\"white\" stroke-width=\"2\" stroke-miterlimit=\"10\"\/>\n            <\/svg>\n        <\/button>\n        <div class=\"j-videoInlinePlayer videoInline__player videoInline__player--show\" data-plyr-provider=\"youtube\" data-plyr-embed-id=\"https:\/\/youtu.be\/6B5qwGhjIVk\"><\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":186,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[119],"tags":[],"class_list":["post-54777","post","type-post","status-publish","hentry","category-behind-the-scenes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come nasce un paio di occhiali? | Stories - https:\/\/www.marcolin.com\/<\/title>\n<meta name=\"description\" content=\"Delle diverse fasi di produzione, tutte invisibili al pubblico, ce n\u2019\u00e8 una particolarmente lunga e delicata. Si chiama burattatura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come nasce un paio di occhiali? | Stories - https:\/\/www.marcolin.com\/\" \/>\n<meta property=\"og:description\" content=\"Delle diverse fasi di produzione, tutte invisibili al pubblico, ce n\u2019\u00e8 una particolarmente lunga e delicata. Si chiama burattatura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/\" \/>\n<meta property=\"og:site_name\" content=\"https:\/\/www.marcolin.com\/\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/marcolinspa\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T09:59:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@marcolineyewear\" \/>\n<meta name=\"twitter:site\" content=\"@marcolineyewear\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#\\\/schema\\\/person\\\/638a4f3e86a17ada8a2438959cfa31b6\"},\"headline\":\"Come nasce un paio di occhiali?\",\"datePublished\":\"2023-09-07T09:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#organization\"},\"articleSection\":[\"Behind the scenes\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/\",\"url\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/\",\"name\":\"Come nasce un paio di occhiali? | Stories - https:\\\/\\\/www.marcolin.com\\\/\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#website\"},\"datePublished\":\"2023-09-07T09:59:00+00:00\",\"description\":\"Delle diverse fasi di produzione, tutte invisibili al pubblico, ce n\u2019\u00e8 una particolarmente lunga e delicata. Si chiama burattatura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/stories\\\/behind-the-scenes\\\/come-nasce-un-paio-di-occhiali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come nasce un paio di occhiali?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/\",\"name\":\"https:\\\/\\\/www.marcolin.com\\\/\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#organization\",\"name\":\"https:\\\/\\\/www.marcolin.com\\\/\",\"url\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.marcolin.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.marcolin.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo.jpg\",\"width\":1360,\"height\":140,\"caption\":\"https:\\\/\\\/www.marcolin.com\\\/\"},\"image\":{\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/marcolinspa\",\"https:\\\/\\\/x.com\\\/marcolineyewear\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/marcolin\",\"http:\\\/\\\/instagram.com\\\/marcolin_eyewear\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/#\\\/schema\\\/person\\\/638a4f3e86a17ada8a2438959cfa31b6\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/093e8f56e2e05ba433bd643cccc1ce426af27708db1f36da4afa7cc0bbc53bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/093e8f56e2e05ba433bd643cccc1ce426af27708db1f36da4afa7cc0bbc53bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/093e8f56e2e05ba433bd643cccc1ce426af27708db1f36da4afa7cc0bbc53bfc?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"sameAs\":[\"http:\\\/\\\/Marcolin.com\"],\"url\":\"https:\\\/\\\/www.marcolin.com\\\/it\\\/author\\\/giovanna-masi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come nasce un paio di occhiali? | Stories - https:\/\/www.marcolin.com\/","description":"Delle diverse fasi di produzione, tutte invisibili al pubblico, ce n\u2019\u00e8 una particolarmente lunga e delicata. Si chiama burattatura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/","og_locale":"it_IT","og_type":"article","og_title":"Come nasce un paio di occhiali? | Stories - https:\/\/www.marcolin.com\/","og_description":"Delle diverse fasi di produzione, tutte invisibili al pubblico, ce n\u2019\u00e8 una particolarmente lunga e delicata. Si chiama burattatura.","og_url":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/","og_site_name":"https:\/\/www.marcolin.com\/","article_publisher":"http:\/\/www.facebook.com\/marcolinspa","article_published_time":"2023-09-07T09:59:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@marcolineyewear","twitter_site":"@marcolineyewear","twitter_misc":{"Scritto da":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/#article","isPartOf":{"@id":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/"},"author":{"name":"Redazione","@id":"https:\/\/www.marcolin.com\/it\/#\/schema\/person\/638a4f3e86a17ada8a2438959cfa31b6"},"headline":"Come nasce un paio di occhiali?","datePublished":"2023-09-07T09:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/"},"wordCount":6,"publisher":{"@id":"https:\/\/www.marcolin.com\/it\/#organization"},"articleSection":["Behind the scenes"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/","url":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/","name":"Come nasce un paio di occhiali? | Stories - https:\/\/www.marcolin.com\/","isPartOf":{"@id":"https:\/\/www.marcolin.com\/it\/#website"},"datePublished":"2023-09-07T09:59:00+00:00","description":"Delle diverse fasi di produzione, tutte invisibili al pubblico, ce n\u2019\u00e8 una particolarmente lunga e delicata. Si chiama burattatura.","breadcrumb":{"@id":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.marcolin.com\/it\/stories\/behind-the-scenes\/come-nasce-un-paio-di-occhiali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.marcolin.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come nasce un paio di occhiali?"}]},{"@type":"WebSite","@id":"https:\/\/www.marcolin.com\/it\/#website","url":"https:\/\/www.marcolin.com\/it\/","name":"https:\/\/www.marcolin.com\/","description":"Just another WordPress site","publisher":{"@id":"https:\/\/www.marcolin.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.marcolin.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.marcolin.com\/it\/#organization","name":"https:\/\/www.marcolin.com\/","url":"https:\/\/www.marcolin.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.marcolin.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.marcolin.com\/wp-content\/uploads\/2022\/10\/Logo.jpg","contentUrl":"https:\/\/www.marcolin.com\/wp-content\/uploads\/2022\/10\/Logo.jpg","width":1360,"height":140,"caption":"https:\/\/www.marcolin.com\/"},"image":{"@id":"https:\/\/www.marcolin.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/marcolinspa","https:\/\/x.com\/marcolineyewear","http:\/\/www.linkedin.com\/company\/marcolin","http:\/\/instagram.com\/marcolin_eyewear"]},{"@type":"Person","@id":"https:\/\/www.marcolin.com\/it\/#\/schema\/person\/638a4f3e86a17ada8a2438959cfa31b6","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/093e8f56e2e05ba433bd643cccc1ce426af27708db1f36da4afa7cc0bbc53bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/093e8f56e2e05ba433bd643cccc1ce426af27708db1f36da4afa7cc0bbc53bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/093e8f56e2e05ba433bd643cccc1ce426af27708db1f36da4afa7cc0bbc53bfc?s=96&d=mm&r=g","caption":"Redazione"},"sameAs":["http:\/\/Marcolin.com"],"url":"https:\/\/www.marcolin.com\/it\/author\/giovanna-masi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/posts\/54777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/users\/186"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/comments?post=54777"}],"version-history":[{"count":0,"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/posts\/54777\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/media?parent=54777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/categories?post=54777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcolin.com\/it\/wp-json\/wp\/v2\/tags?post=54777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}